{"id":3986,"date":"2020-11-15T22:22:31","date_gmt":"2020-11-15T13:22:31","guid":{"rendered":"https:\/\/www.wbsac.org\/?p=3986"},"modified":"2020-11-15T22:22:31","modified_gmt":"2020-11-15T13:22:31","slug":"2020p-exhibition-2nd-end","status":"publish","type":"post","link":"https:\/\/www.wbsac.org\/index.php\/2020\/11\/15\/2020p-exhibition-2nd-end\/","title":{"rendered":"2020\u5e74 WBS\u5199\u771f\u5c55\uff08\u660e\u77f3\u5e02\u7acb\u897f\u90e8\u5e02\u6c11\u4f1a\u9928\uff09\u7d42\u308f\u308a\u307e\u3057\u305f"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.wbsac.org\/wp-content\/uploads\/2020\/11\/201115_\u897f\u90e8\u5e02\u6c11\u4f1a\u9928\u64a4\u53ce.jpg\" alt=\"\" class=\"wp-image-3993\" srcset=\"https:\/\/www.wbsac.org\/wp-content\/uploads\/2020\/11\/201115_\u897f\u90e8\u5e02\u6c11\u4f1a\u9928\u64a4\u53ce.jpg 960w, https:\/\/www.wbsac.org\/wp-content\/uploads\/2020\/11\/201115_\u897f\u90e8\u5e02\u6c11\u4f1a\u9928\u64a4\u53ce-150x113.jpg 150w, https:\/\/www.wbsac.org\/wp-content\/uploads\/2020\/11\/201115_\u897f\u90e8\u5e02\u6c11\u4f1a\u9928\u64a4\u53ce-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>2020\/11\/1\u3088\u308a\u958b\u50ac\u3057\u3066\u3044\u305f\u5199\u771f\u5c55\u304c\u672c\u65e5\uff0811\/15\uff09\u30d5\u30a3\u30ca\u30fc\u30ec\u3092\u8fce\u3048\u307e\u3057\u305f\u3002<br>\u30a2\u30f3\u30b1\u30fc\u30c8\u306f38\u679a\u306e\u6295\u51fd\u304c\u3042\u308a\u3001\u4f5c\u54c1\u306b\u5bfe\u3059\u308b\u52b1\u307e\u3057\u306e\u58f0\u3092\u3044\u305f\u3060\u304d\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3057\u305f\u3002<br>\u4eba\u6c17\u6295\u7968\u306e\u7d50\u679c\u3092\u5831\u544a\u3057\u307e\u3059\u3002<br>\uff08\u30a2\u30f3\u30b1\u30fc\u30c8\u306e\u6295\u51fd\u6570\u306f\u660e\u77f338\u679a\u3001\u59eb\u8def11\u679a\u3067\u3057\u305f\u3002\u591a\u6570\u306e\u6295\u51fd\u3001\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3057\u305f\u3002\uff09<\/p>\n\n\n\n<p>\u00a0<\/p>\n<table style=\"border-collapse: collapse; width: 95.4579%; height: 982px;\">\n<tbody>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; background-color: #000000; height: 74px;\" rowspan=\"2\">\u00a0<\/td>\n<td style=\"width: 61.7725%; height: 74px; background-color: #000000;\" rowspan=\"2\">\u4f5c\u54c1\u540d<\/td>\n<td style=\"width: 23.4624%; height: 37px; background-color: #000000;\" colspan=\"3\">\u4eba\u6c17\u5f97\u7968\u6570<\/td>\n<td style=\"width: 8.62955%; background-color: #000000; height: 74px;\" rowspan=\"2\">\u4eba\u6c17\u9806\u4f4d<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.65631%; height: 37px; background-color: #000000;\">\u59eb\u8def<\/td>\n<td style=\"width: 8.06831%; height: 37px; background-color: #000000;\">\u660e\u77f3<\/td>\n<td style=\"width: 7.73774%; height: 37px; background-color: #000000;\">\u5408\u8a08<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 57px;\">\u901f\u5831<\/td>\n<td style=\"width: 61.7725%; height: 57px;\">\u5c71\u5f62\u770c\u30fb\u5929\u7ae5\u9ad8\u539f\u3067\u64ae\u3063\u305f\u30cd\u30aa\u30ef\u30a4\u30ba\u5f57\u661f<\/td>\n<td style=\"width: 7.65631%; height: 57px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 57px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 57px;\">3\u7968<\/td>\n<td style=\"width: 8.62955%; height: 57px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">1<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">SPACE(\u3068\u3063\u3066\u304a\u304d\u306e\u5b99\u306e\u5834)<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">4\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">2<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u660e\u77f3\u9b5a\u4f4f\u306e\u6d77\u5cb8\u304b\u3089\u898b\u305f\u6708\u3068\uff13\u60d1\u661f\uff08\u6728\u661f\u3000\u91d1\u661f\u3000\u571f\u661f\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">9\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">10\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">3\u4f4d<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">3<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u795e\u6238\u306b\u3082\u3044\u308b\u3088\u3002\u86cd\u306e\u5ddd\u3002<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">15\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">16\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">1\u4f4d<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">4<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u4e2d\u5c3e\u89aa\u6c34\u516c\u5712\u306e\u685c\u3068\u51ac\u306e\u30c0\u30a4\u30e4\u30e2\u30f3\u30c9\uff06\u91d1\u661f<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">8\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">9\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">5<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u714c\u3081\u304f\u30d0\u30f3\u30d3\u306e\u6a2a\u9854<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">6<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u767d\u6a3a\u306e\u6728\u3068\u6669\u79cb\u306e\u5929\u306e\u5ddd<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">8\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">7<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u7acb\u3061\u6607\u308b\u9ec4\u9053\u5149\u3068\u5929\u306e\u5ddd\u306e\u5171\u6f14<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">8<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u30a2\u30e1\u30ea\u30ab\u30f3\u8abf\u306e\uff2d\uff13\uff13\u9280\u6cb3<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">4\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">9<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u304a\u304a\u3050\u307e\u5ea7\u306e\u6e26\u5dfb\u304d\u9280\u6cb3 \uff2d\uff18\uff11<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">4\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">12\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">16\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">1\u4f4d<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">10<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u304b\u307f\u306e\u3051\u5ea7\u306e\u6e26\u5dfb\u9280\u6cb3 \uff2e\uff27\uff23\uff14\uff15\uff16\uff15<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">4\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">11<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u30a8\u30d3\u661f\u96f2\u3068\u5468\u8fba\u306eHII\u9818\u57df<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">12<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u304d\u308a\u3093\u5ea7\u306e\u30d5\u30a7\u30a4\u30b9\u30aa\u30f3\u9280\u6cb3 \uff29\uff23\uff13\uff14\uff12<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">13<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u3070\u3089\u661f\u96f2\uff08\uff2e\uff27\uff23\uff12\uff12\uff14\uff14\u30fb\uff2e\uff27\uff23\uff12\uff12\uff13\uff17-\uff19\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">10\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">10\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">3\u4f4d<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">14<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u304b\u3082\u3081\u661f\u96f2\u3000\uff29\uff23\uff12\uff11\uff17\uff17<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">15<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\uff2d\uff14\uff15\uff08\u30d7\u30ec\u30a2\u30c7\u30b9\u661f\u56e3\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">8\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">16<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u4e09\u88c2\u661f\u96f2\u304b\u3089\u5e72\u6f5f\u661f\u96f2\u4ed8\u8fd1<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">17<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u30b1\u30d5\u30a7\u30a6\u30b9\u5ea7\uff36\uff44\uff22\uff11\uff14\uff12\uff08\u901a\u79f0\u3000\u8c61\u306e\u9f3b\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">6\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">18<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u5317\u30a2\u30e1\u30ea\u30ab\u661f\u96f2\u304b\u3089\u30da\u30ea\u30ab\u30f3\u661f\u96f2\u4ed8\u8fd1<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">19<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\uff2d\uff12\uff17\uff08\u4e9c\u9234\u72b6\u661f\u96f2\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">4\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">7\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">20<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u30aa\u30ea\u30aa\u30f3\u5ea7\u306e\u99ac\u982d\u661f\u96f2<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">7\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">9\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">21<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\uff2d\uff12\uff10\uff08\u4e09\u88c2\u661f\u96f2\uff09\u3068\uff2d\uff12\uff11\uff08\u6563\u958b\u661f\u56e3\uff09<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">22<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\u30cf\u30fc\u30c8\u661f\u96f2\u4e2d\u5fc3\u90e8\u3000Melotte\uff11\uff15<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">1\u7968<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">3\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td style=\"width: 7.3246%; height: 37px;\">23<\/td>\n<td style=\"width: 61.7725%; height: 37px;\">\uff2e\uff27\uff23\uff16\uff11\uff18\uff18\u3068\u5468\u8fba\u306e\u6697\u9ed2\u5e2f<\/td>\n<td style=\"width: 7.65631%; height: 37px;\">\u00a0<\/td>\n<td style=\"width: 8.06831%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 7.73774%; height: 37px;\">2\u7968<\/td>\n<td style=\"width: 8.62955%; height: 37px;\">\u00a0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2020\/11\/1\u3088\u308a\u958b\u50ac\u3057\u3066\u3044\u305f\u5199\u771f\u5c55\u304c\u672c\u65e5\uff0811\/15\uff09\u30d5\u30a3\u30ca\u30fc\u30ec\u3092\u8fce\u3048\u307e\u3057\u305f\u3002\u30a2\u30f3\u30b1\u30fc\u30c8\u306f38\u679a\u306e\u6295\u51fd\u304c\u3042\u308a\u3001\u4f5c\u54c1\u306b\u5bfe\u3059\u308b\u52b1\u307e\u3057\u306e\u58f0\u3092\u3044\u305f\u3060\u304d\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3057\u305f\u3002\u4eba\u6c17\u6295\u7968\u306e\u7d50\u679c\u3092\u5831\u544a\u3057\u307e\u3059\u3002\uff08\u30a2\u30f3\u30b1\u30fc\u30c8\u306e\u6295\u51fd\u6570 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[65],"class_list":["post-3986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-p-exhibition","tag-2020y"],"_links":{"self":[{"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/posts\/3986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/comments?post=3986"}],"version-history":[{"count":6,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/posts\/3986\/revisions"}],"predecessor-version":[{"id":3994,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/posts\/3986\/revisions\/3994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/media\/3993"}],"wp:attachment":[{"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/media?parent=3986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/categories?post=3986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wbsac.org\/index.php\/wp-json\/wp\/v2\/tags?post=3986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}